{"id":2034,"date":"2023-10-24T03:59:05","date_gmt":"2023-10-24T01:59:05","guid":{"rendered":"https:\/\/anniepempinello.com\/disegni\/lille-la-vie-la-ville\/"},"modified":"2023-11-24T00:14:51","modified_gmt":"2023-11-23T23:14:51","slug":"lille-la-vie-la-ville","status":"publish","type":"page","link":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/","title":{"rendered":"Lille la vie la ville"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row css=&#8221;.vc_custom_1698715964017{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;nomo&#8221;][vc_column width=&#8221;2\/5&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;150&#8243;][vc_row_inner][vc_column_inner animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;200&#8243;][vc_single_image image=&#8221;1549&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;nomecatpng&#8221;][vc_column_text]<\/p>\n<div class=\"testo testodescrica\">The northern light, not cold, the lively and dreamy air of the city of Lille.<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1739&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 001<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-001\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;600&#8243;][vc_single_image image=&#8221;1740&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 002<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-002\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;900&#8243;][vc_single_image image=&#8221;1741&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 003<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-003\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1200&#8243;][vc_single_image image=&#8221;1742&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 004<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-004\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1500&#8243;][vc_single_image image=&#8221;1743&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 005<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-005\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1900&#8243;][vc_single_image image=&#8221;1744&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 006<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-006\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1745&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 007<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-007\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;600&#8243;][vc_single_image image=&#8221;1746&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 008<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-008\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;900&#8243;][vc_single_image image=&#8221;1747&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 009<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-009\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1748&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 010<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-010\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;600&#8243;][vc_single_image image=&#8221;1749&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 011<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-011\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;900&#8243;][vc_single_image image=&#8221;1750&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 012<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-012\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1751&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 013<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-013\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;600&#8243;][vc_single_image image=&#8221;1752&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 014<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-014\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;900&#8243;][vc_single_image image=&#8221;1753&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 015<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-015\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1754&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 016<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-016\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;600&#8243;][vc_single_image image=&#8221;1755&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 017<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-017\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;900&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1698715971683{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;node&#8221;][vc_column width=&#8221;2\/5&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;150&#8243;][vc_row_inner][vc_column_inner animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;200&#8243;][vc_single_image image=&#8221;1585&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;nomecatpng&#8221;][vc_column_text]<\/p>\n<div class=\"testo testodescrica\">La luce nordica, non fredda, l&#8217;aria briosa e sognante della citt\u00e0 di Lille.<\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_row_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1739&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 001<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-001\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;600&#8243;][vc_single_image image=&#8221;1740&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 002<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-002\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;900&#8243;][vc_single_image image=&#8221;1741&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 003<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-003\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;1742&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 004<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-004\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1500&#8243;][vc_single_image image=&#8221;1743&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 005<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-005\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1900&#8243;][vc_single_image image=&#8221;1744&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 006<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-006\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1200&#8243;][vc_single_image image=&#8221;1745&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 007<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-007\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;1746&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 008<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-008\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1500&#8243;][vc_single_image image=&#8221;1747&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 009<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-009\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1900&#8243;][vc_single_image image=&#8221;1748&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 010<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-010\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1200&#8243;][vc_single_image image=&#8221;1749&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 011<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-011\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;1750&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 012<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-012\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1500&#8243;][vc_single_image image=&#8221;1751&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 013<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-013\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1900&#8243;][vc_single_image image=&#8221;1752&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 014<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-014\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1200&#8243;][vc_single_image image=&#8221;1753&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 015<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-015\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243;][vc_single_image image=&#8221;1754&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 016<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-016\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner el_class=&#8221;margintoprigadis&#8221;][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1500&#8243;][vc_single_image image=&#8221;1755&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text]<\/p>\n<div class=\"titolosingolodisegno\">Lille &#8211; 017<\/div>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<div class=\"pulsanteiwant\"><a href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/lille-017\/\"><span class=\"boldlettera\">I<\/span> WANT <span class=\"boldlettera\">I<\/span>T!<\/a><\/div>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1900&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;1200&#8243;][\/vc_column_inner][vc_column_inner el_class=&#8221;aduemob&#8221; width=&#8221;1\/4&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1698715964017{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;nomo&#8221;][vc_column width=&#8221;2\/5&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;150&#8243;][vc_row_inner][vc_column_inner animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;200&#8243;][vc_single_image image=&#8221;1549&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;nomecatpng&#8221;][vc_column_text] The northern light, not cold, the lively and dreamy air of the city of Lille. [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1739&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text] Lille &#8211; 001 [\/vc_column_text][vc_column_text] I WANT IT! [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1993,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2034","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lille la vie la ville - Anniepempinello<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lille la vie la ville - Anniepempinello\" \/>\n<meta property=\"og:description\" content=\"[vc_row css=&#8221;.vc_custom_1698715964017{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;nomo&#8221;][vc_column width=&#8221;2\/5&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;150&#8243;][vc_row_inner][vc_column_inner animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;200&#8243;][vc_single_image image=&#8221;1549&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;nomecatpng&#8221;][vc_column_text] The northern light, not cold, the lively and dreamy air of the city of Lille. [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1739&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text] Lille &#8211; 001 [\/vc_column_text][vc_column_text] I WANT IT! [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/\" \/>\n<meta property=\"og:site_name\" content=\"Anniepempinello\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-23T23:14:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/\",\"url\":\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/\",\"name\":\"Lille la vie la ville - Anniepempinello\",\"isPartOf\":{\"@id\":\"https:\/\/anniepempinello.com\/en\/#website\"},\"datePublished\":\"2023-10-24T01:59:05+00:00\",\"dateModified\":\"2023-11-23T23:14:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/anniepempinello.com\/en\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Designs\",\"item\":\"https:\/\/anniepempinello.com\/en\/designs\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Lille la vie la ville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/anniepempinello.com\/en\/#website\",\"url\":\"https:\/\/anniepempinello.com\/en\/\",\"name\":\"Anniepempinello\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/anniepempinello.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lille la vie la ville - Anniepempinello","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/","og_locale":"en_US","og_type":"article","og_title":"Lille la vie la ville - Anniepempinello","og_description":"[vc_row css=&#8221;.vc_custom_1698715964017{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; el_class=&#8221;nomo&#8221;][vc_column width=&#8221;2\/5&#8243; enable_sticky=&#8221;true&#8221; sticky_offset=&#8221;150&#8243;][vc_row_inner][vc_column_inner animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;100&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;200&#8243;][vc_single_image image=&#8221;1549&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; el_class=&#8221;nomecatpng&#8221;][vc_column_text] The northern light, not cold, the lively and dreamy air of the city of Lille. [\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;3\/5&#8243;][vc_row_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221; animation_in_offset=&#8221;90&#8243; animation_in_duration=&#8221;1000&#8243; animation_in_delay=&#8221;300&#8243;][vc_single_image image=&#8221;1739&#8243; img_size=&#8221;full&#8221; el_class=&#8221;immadis&#8221;][vc_column_text] Lille &#8211; 001 [\/vc_column_text][vc_column_text] I WANT IT! [\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; animation_in_type=&#8221;transition.fadeIn&#8221;","og_url":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/","og_site_name":"Anniepempinello","article_modified_time":"2023-11-23T23:14:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/","url":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/","name":"Lille la vie la ville - Anniepempinello","isPartOf":{"@id":"https:\/\/anniepempinello.com\/en\/#website"},"datePublished":"2023-10-24T01:59:05+00:00","dateModified":"2023-11-23T23:14:51+00:00","breadcrumb":{"@id":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/anniepempinello.com\/en\/designs\/lille-la-vie-la-ville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/anniepempinello.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"Designs","item":"https:\/\/anniepempinello.com\/en\/designs\/"},{"@type":"ListItem","position":3,"name":"Lille la vie la ville"}]},{"@type":"WebSite","@id":"https:\/\/anniepempinello.com\/en\/#website","url":"https:\/\/anniepempinello.com\/en\/","name":"Anniepempinello","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/anniepempinello.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/pages\/2034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/comments?post=2034"}],"version-history":[{"count":3,"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/pages\/2034\/revisions"}],"predecessor-version":[{"id":2423,"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/pages\/2034\/revisions\/2423"}],"up":[{"embeddable":true,"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/pages\/1993"}],"wp:attachment":[{"href":"https:\/\/anniepempinello.com\/en\/wp-json\/wp\/v2\/media?parent=2034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}